{"id":12104,"date":"2025-01-10T09:33:43","date_gmt":"2025-01-10T08:33:43","guid":{"rendered":"https:\/\/swisschange.ch\/?p=12104"},"modified":"2025-01-10T09:37:27","modified_gmt":"2025-01-10T08:37:27","slug":"2025-laender-oder-sektorenselektion","status":"publish","type":"post","link":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/","title":{"rendered":"2025: L\u00c4NDER- ODER SEKTORENSELEKTION?"},"content":{"rendered":"\n<p>EMR Januar 2025<\/p>\n\n\n\n<p>Liebe Leserinnen, und Leser,<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">WAS HABEN WIR AUS DEM JAHR 2024 GELERNT?<\/h2>\n\n\n\n<p>Die meisten von uns werden sich sicher daran erinnern, dass wir im Jahr 2024 die Bedeutung der L\u00e4nder- und W\u00e4hrungsauswahl stark betont haben. Wir denken im Zusammenhang an unsere wiederholten Aussagen betreffend Aktienallokation und entsprechendem Fokus auf W\u00e4hrungen als prim\u00e4re Determinanten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">DETAILS SIND WICHTIG<\/h2>\n\n\n\n<p>Im Verlauf des Jahres 2024 haben wir immer wieder darauf hingewiesen, dass weder das Argumentieren der Zentralbanken \u00fcber die Notwendigkeit von Zinsinterventionen noch koh\u00e4rente Inflations\u00e4ngste die Hauptursache f\u00fcr das Auf und Ab des Aktienuniversums waren. Vielmehr ist dies die erhebliche technologische Kluft zwischen den USA und dem Rest des Anlageuniversums. K\u00fcrzlich stiessen wir auf eine \u00fcberraschend klare und h\u00f6chst provokante Darstellung der Entwicklung des Aktienuniversums, und zwar auf einen Artikel von Andrew McAfee: \u201cThe EU faces a huge innovation gap\u201d vom MIT. Der Artikel zeigt eine riesige L\u00fccke auf und stellt diese mit der folgenden Graphik deutlich dar. Wir konnten es nicht so klar zu visualisieren, wie es Andrew McAfee 1macht. Lassen Sie uns daher in seine Fussstapfen treten, um eine L\u00f6sung f\u00fcr die zuk\u00fcnftige Entwicklung des Aktienmarktes zu finden. Die grafische Darstellung zeigt Folgendes:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2025\/01\/EMR25_Jan_DE02.jpg\" alt=\"\" class=\"wp-image-12112\" style=\"object-fit:contain;width:800px;height:450px\" srcset=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2025\/01\/EMR25_Jan_DE02.jpg 800w, https:\/\/swisschange.ch\/wp-content\/uploads\/2025\/01\/EMR25_Jan_DE02-300x169.jpg 300w, https:\/\/swisschange.ch\/wp-content\/uploads\/2025\/01\/EMR25_Jan_DE02-768x432.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Bei der Analyse der Grafik stehen wir vor einem sehr merkw\u00fcrdigen Dilemma. W\u00e4hrend des gesamten Jahres 2024 haben wir der offiziellen und weit verbreiteten Annahme widersprochen, dass die Konzentration der Zentralbanken auf das Zinsmanagement sowohl das Inflations- als auch das Wachstumsdilemma als Hauptdeterminante des Anlageuniversums l\u00f6sen w\u00fcrde.<\/p>\n\n\n\n<p>Bei genauer Betrachtung der Graphik von Andrew McAfee stellen wir mit grosser Freude fest: Weder die prim\u00e4re Konzentration der Zentralbanken auf Zinsanpassungen noch die koh\u00e4renten Inflations\u00e4ngste sind die wichtigste und entscheidende Ursache f\u00fcr das Auf und Ab der Aktienm\u00e4rkt. Vielmehr ist dies die betr\u00e4chtliche technologische Kluft zwischen den USA und dem Rest des Anlageuniversums. In seinem Artikel verdeutlicht Andrew McAfee die grosse Kluft zwischen der EU und den USA auf eine recht eigene Weise. Die Graphik visualisiert deutlich, was wir mit Worten beschrieben hatten.<\/p>\n\n\n\n<p>Folgen wir seiner Analyse mit dem Ziel, einen Anhaltspunkt f\u00fcr die m\u00f6glichen Entwicklungen am Aktienmarkt zu finden, dann l\u00e4sst sich Folgendes ableiten:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>In letzter Zeit haben f\u00fcnf Aktien in Bezug auf Gr\u00f6sse und Leistung erstaunliche Gewinne erzielt, in Mrd. USD ausgedr\u00fcckt:<\/li>\n<\/ol>\n\n\n\n<p>&#8211; &nbsp;&nbsp; Apple:&nbsp;3&#8217;751<br>&#8211;&nbsp;&nbsp;&nbsp; Microsoft: 3&#8217;268<br>&#8211;&nbsp;&nbsp;&nbsp; Nvidia:  3&#8217;208<br>&#8211;&nbsp;&nbsp;&nbsp; Amazon: 2\u2019363<br>&#8211;&nbsp;&nbsp;&nbsp; Google: 2\u2019347<\/p>\n\n\n\n<p>2. &nbsp; Andere Aktienwerte folgen mit etwas geringeren Wachstum, aber immer noch mit beachtlichen Wachstumsraten.<\/p>\n\n\n\n<p>3.&nbsp;&nbsp; Was im erw\u00e4hnten Artikel beschrieben wird, ist nicht nur die grosse Kluft zwischen den USA und Europa, sondern vielmehr auch, dass den europ\u00e4ischen M\u00e4rkten im Vergleich zu den USA kaum Chancen haben, die n\u00e4chsten Riesen zu werden.<\/p>\n\n\n\n<p>4.&nbsp;&nbsp; Was unser EUR-Engagement angeht, so sind wir \u00fcber die politischen Unsicherheiten in Frankreich und Deutschland recht besorgt.<\/p>\n\n\n\n<p>Kontextbezogen f\u00e4llt es uns schwer zu verstehen, warum die oben genannten Unterschiede nicht ernster genommen wurden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">AUSBLICK 2025<\/h2>\n\n\n\n<p>In Anbetracht des oben beschriebenen wirtschaftlichen, politischen und sozialen Umfelds sieht der Ausblick f\u00fcr 2025 wie eine \u201esehr komplizierte und eine ziemlich schwierige Aufgabe\u201d aus, nicht wahr? Sind wir immer noch der Ansicht, dass die Inflation der Hauptfeind der politischen Entscheidungstr\u00e4ger und\/oder Investoren ist und daher beseitigt oder zumindest einged\u00e4mmt werden sollte, oder beginnen wir zu pr\u00fcfen, welche Wirtschaftssektoren bessere Ergebnisse versprechen?<\/p>\n\n\n\n<p>Die Ungleichheiten werden nicht ernster genommen als der Versuch, die Inflation mit Hilfe von Zinsanpassungen zu bek\u00e4mpfen.<\/p>\n\n\n\n<p>F\u00fcr den Fall, dass sich die Beh\u00f6rden weiterhin auf die Inflationsbek\u00e4mpfung durch Zinsmanagement konzentrieren, bleiben die Renditeaussichten eher ged\u00e4mpft. Warum, mag man sich fragen? In Zeiten des Krieges, der anhaltenden russischen Invasion in der Ukraine und \u00e4hnlich absurder Entwicklungen im Nahen Osten k\u00f6nnte man sich fragen, wie \u00c4nderungen der Zinss\u00e4tze den Preis f\u00fcr Roh\u00f6l, insbesondere in Europa, senken k\u00f6nnten? Wir sollten nicht vergessen, dass sich zwei der gr\u00f6ssten europ\u00e4ischen Volkswirtschaften (Frankreich und Deutschland) in einer sehr verworrenen politischen Situation befinden, n\u00e4mlich einem gravierenden Mangel an wirtschaftlicher, sozialer und politischer F\u00fchrung. Wir halten diesen Kontext f\u00fcr sehr problematisch, wenn nicht sogar f\u00fcr gef\u00e4hrlich.<\/p>\n\n\n\n<p>Falls die Anleger beginnen sollten, sich auf Sektoren wie die Technologie zu konzentrieren, wie es in den USA der Fall war und weiterhin sein wird, k\u00f6nnten sich die Aussichten deutlich \u201eaufhellen\u201d. Sicherlich k\u00f6nnen wir an diesem Scheideweg nicht vorhersagen, was die neue US-Regierung tun wird, da die M\u00f6glichkeit einer \u201eAmerika First\u201d-Politik im Vordergrund steht.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ZUSAMMENFASSEND<\/h2>\n\n\n\n<p>Trotz aller Prognoseschwierigkeiten beim Timing bevorzugen wir als Schweizer Franken-Anleger unseren Heimatmarkt vor allem aus W\u00e4hrungsgr\u00fcnden. Wir gehen davon aus, dass der CHF, nach wie vor sehr gefragt sein wird.<\/p>\n\n\n\n<p>Die internationale Diversifikation spricht, im Einklang mit den technologischen Entwicklungen, einmal mehr f\u00fcr Investitionen in den USA.<\/p>\n\n\n\n<p>Was das EUR-Engagement betrifft, so sind wir etwas besorgt \u00fcber die politischen Unsicherheiten in Frankreich und Deutschland.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">EIN FROHES &amp; ERFOLGREICHES NEUES JAHR 2025<\/h2>\n\n\n\n<p>Anregungen sind willkommen.<\/p>\n<span class=\"synved-social-container synved-social-container-share\"><a class=\"synved-social-button synved-social-button-share synved-social-size-24 synved-social-resolution-single synved-social-provider-facebook nolightbox\" data-provider=\"facebook\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fswisschange.ch%2Fit%2Fwp-json%2Fwp%2Fv2%2Fposts%2F12104%2F&#038;t=2025%3A%20L%C3%84NDER-%20ODER%20SEKTORENSELEKTION%3F&#038;s=100&#038;p&#091;url&#093;=https%3A%2F%2Fswisschange.ch%2Fit%2Fwp-json%2Fwp%2Fv2%2Fposts%2F12104%2F&#038;p&#091;images&#093;&#091;0&#093;=https%3A%2F%2Fswisschange.ch%2Fwp-content%2Fuploads%2F2025%2F01%2FEMR25_Jan_DE02.jpg&#038;p&#091;title&#093;=2025%3A%20L%C3%84NDER-%20ODER%20SEKTORENSELEKTION%3F\" style=\"font-size: 0px;width:24px;height:24px;margin:0;margin-bottom:10px;margin-right:10px\"><img decoding=\"async\" alt=\"Facebook\" title=\"Share on Facebook\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"24\" height=\"24\" style=\"display: inline;width:24px;height:24px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/swisschange.ch\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/48x48\/facebook.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-24 synved-social-resolution-single synved-social-provider-twitter nolightbox\" data-provider=\"twitter\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fswisschange.ch%2Fit%2Fwp-json%2Fwp%2Fv2%2Fposts%2F12104%2F&#038;text=Hey%20check%20this%20out\" style=\"font-size: 0px;width:24px;height:24px;margin:0;margin-bottom:10px;margin-right:10px\"><img decoding=\"async\" alt=\"twitter\" title=\"Share on Twitter\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"24\" height=\"24\" style=\"display: inline;width:24px;height:24px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/swisschange.ch\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/48x48\/twitter.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-24 synved-social-resolution-single synved-social-provider-linkedin nolightbox\" data-provider=\"linkedin\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fswisschange.ch%2Fit%2Fwp-json%2Fwp%2Fv2%2Fposts%2F12104%2F&#038;title=2025%3A%20L%C3%84NDER-%20ODER%20SEKTORENSELEKTION%3F\" style=\"font-size: 0px;width:24px;height:24px;margin:0;margin-bottom:10px;margin-right:10px\"><img loading=\"lazy\" decoding=\"async\" alt=\"linkedin\" title=\"Share on Linkedin\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"24\" height=\"24\" style=\"display: inline;width:24px;height:24px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/swisschange.ch\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/48x48\/linkedin.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-24 synved-social-resolution-single synved-social-provider-mail nolightbox\" data-provider=\"mail\" rel=\"nofollow\" title=\"Share by email\" href=\"mailto:?subject=2025%3A%20L%C3%84NDER-%20ODER%20SEKTORENSELEKTION%3F&#038;body=Hey%20check%20this%20out:%20https%3A%2F%2Fswisschange.ch%2Fit%2Fwp-json%2Fwp%2Fv2%2Fposts%2F12104%2F\" style=\"font-size: 0px;width:24px;height:24px;margin:0;margin-bottom:10px\"><img loading=\"lazy\" decoding=\"async\" alt=\"mail\" title=\"Share by email\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"24\" height=\"24\" style=\"display: inline;width:24px;height:24px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/swisschange.ch\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/48x48\/mail.png\" \/><\/a><\/span>","protected":false},"excerpt":{"rendered":"<p>Die meisten von uns werden sich sicher daran erinnern, dass wir im Jahr 2024 die Bedeutung der L\u00e4nder- und W\u00e4hrungsauswahl stark betont haben. Wir denken im Zusammenhang an unsere wiederholten Aussagen betreffend Aktienallokation und entsprechendem Fokus auf W\u00e4hrungen als prim\u00e4re Determinanten.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-12104","post","type-post","status-publish","format-standard","hentry","category-emr"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Adriano Zanoni\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SWISSCHANGE Financial Services AG | Hypotheken und Verm\u00f6gensverwaltung\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"2025: L\u00c4NDER- ODER SEKTORENSELEKTION? | SWISSCHANGE Financial Services AG\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2018\/10\/Home_Swisschange.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2018\/10\/Home_Swisschange.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-10T08:33:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-10T08:37:27+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swisschange\/\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#article\",\"name\":\"2025: L\\u00c4NDER- ODER SEKTORENSELEKTION? | SWISSCHANGE Financial Services AG\",\"headline\":\"2025: L\\u00c4NDER- ODER SEKTORENSELEKTION?\",\"author\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/author\\\/zanoni\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/EMR25_Jan_DE02.jpg\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#articleImage\",\"width\":800,\"height\":450},\"datePublished\":\"2025-01-10T09:33:43+01:00\",\"dateModified\":\"2025-01-10T09:37:27+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#webpage\"},\"articleSection\":\"EMR, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/category\\\/emr\\\/#listItem\",\"name\":\"EMR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/category\\\/emr\\\/#listItem\",\"position\":2,\"name\":\"EMR\",\"item\":\"https:\\\/\\\/swisschange.ch\\\/category\\\/emr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#listItem\",\"name\":\"2025: L\\u00c4NDER- ODER SEKTORENSELEKTION?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#listItem\",\"position\":3,\"name\":\"2025: L\\u00c4NDER- ODER SEKTORENSELEKTION?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/category\\\/emr\\\/#listItem\",\"name\":\"EMR\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/#organization\",\"name\":\"SWISSCHANGE Financial Services AG\",\"description\":\"Hypotheken und Verm\\u00f6gensverwaltung\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/\",\"telephone\":\"+41612640050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/JCSCWM55-20-Jahre-Logo.svg\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#organizationLogo\",\"width\":269,\"height\":68,\"caption\":\"SWISSCHANGE Financial Services AG\"},\"image\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swisschange\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/38153551\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/author\\\/zanoni\\\/#author\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/author\\\/zanoni\\\/\",\"name\":\"Adriano Zanoni\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#webpage\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/\",\"name\":\"2025: L\\u00c4NDER- ODER SEKTORENSELEKTION? | SWISSCHANGE Financial Services AG\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/2025\\\/01\\\/10\\\/2025-laender-oder-sektorenselektion\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/author\\\/zanoni\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/author\\\/zanoni\\\/#author\"},\"datePublished\":\"2025-01-10T09:33:43+01:00\",\"dateModified\":\"2025-01-10T09:37:27+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/\",\"name\":\"SWISSCHANGE Financial Services AG\",\"description\":\"Hypotheken und Verm\\u00f6gensverwaltung\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>2025: L\u00c4NDER- ODER SEKTORENSELEKTION? | SWISSCHANGE Financial Services AG<\/title>\n\n","aioseo_head_json":{"title":"2025: L\u00c4NDER- ODER SEKTORENSELEKTION? | SWISSCHANGE Financial Services AG","description":"","canonical_url":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#article","name":"2025: L\u00c4NDER- ODER SEKTORENSELEKTION? | SWISSCHANGE Financial Services AG","headline":"2025: L\u00c4NDER- ODER SEKTORENSELEKTION?","author":{"@id":"https:\/\/swisschange.ch\/it\/author\/zanoni\/#author"},"publisher":{"@id":"https:\/\/swisschange.ch\/it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/swisschange.ch\/wp-content\/uploads\/2025\/01\/EMR25_Jan_DE02.jpg","@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#articleImage","width":800,"height":450},"datePublished":"2025-01-10T09:33:43+01:00","dateModified":"2025-01-10T09:37:27+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#webpage"},"isPartOf":{"@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#webpage"},"articleSection":"EMR, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/swisschange.ch\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/category\/emr\/#listItem","name":"EMR"}},{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/category\/emr\/#listItem","position":2,"name":"EMR","item":"https:\/\/swisschange.ch\/category\/emr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#listItem","name":"2025: L\u00c4NDER- ODER SEKTORENSELEKTION?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/it\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#listItem","position":3,"name":"2025: L\u00c4NDER- ODER SEKTORENSELEKTION?","previousItem":{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/category\/emr\/#listItem","name":"EMR"}}]},{"@type":"Organization","@id":"https:\/\/swisschange.ch\/it\/#organization","name":"SWISSCHANGE Financial Services AG","description":"Hypotheken und Verm\u00f6gensverwaltung","url":"https:\/\/swisschange.ch\/it\/","telephone":"+41612640050","logo":{"@type":"ImageObject","url":"https:\/\/swisschange.ch\/wp-content\/uploads\/2020\/01\/JCSCWM55-20-Jahre-Logo.svg","@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#organizationLogo","width":269,"height":68,"caption":"SWISSCHANGE Financial Services AG"},"image":{"@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/swisschange\/","https:\/\/www.linkedin.com\/company\/38153551\/"]},{"@type":"Person","@id":"https:\/\/swisschange.ch\/it\/author\/zanoni\/#author","url":"https:\/\/swisschange.ch\/it\/author\/zanoni\/","name":"Adriano Zanoni"},{"@type":"WebPage","@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#webpage","url":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/","name":"2025: L\u00c4NDER- ODER SEKTORENSELEKTION? | SWISSCHANGE Financial Services AG","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/swisschange.ch\/it\/#website"},"breadcrumb":{"@id":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/#breadcrumblist"},"author":{"@id":"https:\/\/swisschange.ch\/it\/author\/zanoni\/#author"},"creator":{"@id":"https:\/\/swisschange.ch\/it\/author\/zanoni\/#author"},"datePublished":"2025-01-10T09:33:43+01:00","dateModified":"2025-01-10T09:37:27+01:00"},{"@type":"WebSite","@id":"https:\/\/swisschange.ch\/it\/#website","url":"https:\/\/swisschange.ch\/it\/","name":"SWISSCHANGE Financial Services AG","description":"Hypotheken und Verm\u00f6gensverwaltung","inLanguage":"it-IT","publisher":{"@id":"https:\/\/swisschange.ch\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"SWISSCHANGE Financial Services AG | Hypotheken und Verm\u00f6gensverwaltung","og:type":"article","og:title":"2025: L\u00c4NDER- ODER SEKTORENSELEKTION? | SWISSCHANGE Financial Services AG","og:url":"https:\/\/swisschange.ch\/it\/2025\/01\/10\/2025-laender-oder-sektorenselektion\/","og:image":"https:\/\/swisschange.ch\/wp-content\/uploads\/2018\/10\/Home_Swisschange.jpg","og:image:secure_url":"https:\/\/swisschange.ch\/wp-content\/uploads\/2018\/10\/Home_Swisschange.jpg","og:image:width":1500,"og:image:height":1001,"article:published_time":"2025-01-10T08:33:43+00:00","article:modified_time":"2025-01-10T08:37:27+00:00","article:publisher":"https:\/\/www.facebook.com\/swisschange\/"},"aioseo_meta_data":{"post_id":"12104","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-22 09:53:08","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2025-01-10 08:30:50","updated":"2026-05-22 09:53:08"},"_links":{"self":[{"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/posts\/12104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/comments?post=12104"}],"version-history":[{"count":0,"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/posts\/12104\/revisions"}],"wp:attachment":[{"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/media?parent=12104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/categories?post=12104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swisschange.ch\/it\/wp-json\/wp\/v2\/tags?post=12104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}