{"id":4265,"date":"2021-10-26T09:04:47","date_gmt":"2021-10-26T07:04:47","guid":{"rendered":"https:\/\/swisschange.ch\/?p=4265"},"modified":"2021-10-26T10:27:55","modified_gmt":"2021-10-26T08:27:55","slug":"erforderliche-hausaufgaben","status":"publish","type":"post","link":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/","title":{"rendered":"Erforderliche Hausaufgaben"},"content":{"rendered":"\n<p>EMR Oktober 2021<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Gro\u00dfe Umw\u00e4lzungen schaffen gro\u00dfe Investitionsm\u00f6glichkeiten<\/h2>\n\n\n\n<p>Sehr geehrte Leserin, sehr geehrter Leser <\/p>\n\n\n\n<p>Die Investitionsaussichten sind eher d\u00fcster, was vor allem \u00ad\u2013 aber nicht nur \u2013 auf die r\u00fcckl\u00e4ufige Produktivit\u00e4t, auf Angst vor steigender Inflation, eine hohe und wachsende Staatsverschuldung sowie auf \u201cungerechtfertigte\u201d \u00c4ngste vor einer baldigen Korrektur am Aktienmarkt zur\u00fcckzuf\u00fchren ist.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_1-1024x713.png\" alt=\"\" class=\"wp-image-4266\" width=\"550\" srcset=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_1-1024x713.png 1024w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_1-300x209.png 300w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_1-768x534.png 768w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_1.png 1496w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption>Was sagt die Grafik der indexierten Aktien-indizes aus?<br><br>Schlechteste Wertentwicklung: NIKKEI<br>Mittelm\u00e4\u00dfige Wertentwicklung. UKX und CAC<br>Beste Performance: SPI, DAX und DJIA.<br>Fragezeichen bez\u00fcglich Produktivit\u00e4t und was noch?<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Warum der Fokus auf die Produktivit\u00e4t?<\/h2>\n\n\n\n<p>Im Laufe der Jahre haben wir gelernt, dass sich die leistungsst\u00e4rksten Unternehmen (hier durch den jeweiligen Aktienindex repr\u00e4sentiert) in gewisser Weise durch das Zusammenspiel von Produktivit\u00e4t, Inflationswachstum und W\u00e4hrungsentwicklung quantifizieren lassen. In letzter Zeit wurden die Produktivit\u00e4tsgewinne jedoch zunehmend durch defizitfinanzierte Ausgaben der Regierungen behindert. Es ist eine Tatsache, dass in der Vergangenheit diejenigen Wirtschaftszweige einen bedeutenden Aufschwung erlebt haben, die in der Lage waren, ihre Produktivit\u00e4t zu verbessern und gleichzeitig (durch Innovation und technologischen Fortschritt) \u201cneue\u201d Ausr\u00fcstungen bereitzustellen. Welche Rolle spielten dabei die W\u00e4hrungen? Das ist eine interessante Frage, nicht wahr? In diesem Sinne \u00fcberrascht es uns nicht, dass der SPI, der DJIA und der DAX im Vergleich zum NIKKEI, dem UKX und dem CAC-Index so unterschiedlich abschneiden. Wir gehen davon aus, dass die Aktienm\u00e4rkte kein Instrument zur Inflationsabsicherung sind, sondern eher eine Spielwiese f\u00fcr W\u00e4hrungsspezialisten! Aus der Graphik zum realen BIP l\u00e4sst sich ableiten, dass die Probleme, die den derzeitigen technologischen Fortschritt beherrschen, eine schwierige Identifizierung der Unternehmen und Branchen mit den gr\u00f6\u00dften potenziellen F\u00e4higkeiten zur L\u00f6sung der Produktivit\u00e4tsprobleme, Inflationserwartungen und W\u00e4hrungsreaktionen erfordern. Wir konzentrieren uns also weiterhin auf die Innovationskraft der einzelnen Unternehmen und\/oder Wirtschaftszweige. Somit sollte der Schwerpunkt auf die Innovationskraft gesetzt werden und dies als Gegengewicht zur Zerst\u00f6rungskraft.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_2-1024x667.png\" alt=\"\" class=\"wp-image-4270\" width=\"550\" srcset=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_2-1024x667.png 1024w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_2-300x195.png 300w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_2-768x500.png 768w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_2-1536x1000.png 1536w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_2.png 1883w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Die verf\u00fcgbaren Daten zum realen BIP der f\u00fcnf Industriel\u00e4nder deuten darauf hin, dass es seit Anfang der 1980er Jahre nie eine \u00e4hnliche Korrektur gegeben hat, mit Ausnahme des Zeitraums von 2008 bis Anfang 2010!<\/p>\n\n\n\n<p>Die Grafik zeigt auf, dass die Schweizer Wirtschaft mit einer  \u201csignifikanten\u201d Verz\u00f6gerung auf die Abw\u00e4rtskorrekturen des realen BIP in den USA, Deutschland und dem Vereinigten K\u00f6nigreich reagiert hat. Die Leistung Japans ist in der Rezessionsperiode 2007-2010 deutlich ausgepr\u00e4gter.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"267\" src=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_3-300x267.png\" alt=\"\" data-id=\"4274\" data-full-url=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_3.png\" data-link=\"https:\/\/swisschange.ch\/?attachment_id=4274\" class=\"wp-image-4274\" srcset=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_3-300x267.png 300w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_3-768x685.png 768w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_3-1024x913.png 1024w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_3.png 1079w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"300\" height=\"273\" src=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_4-300x273.png\" alt=\"\" data-id=\"4278\" data-full-url=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_4.png\" data-link=\"https:\/\/swisschange.ch\/?attachment_id=4278\" class=\"wp-image-4278\" srcset=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_4-300x273.png 300w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_4-768x700.png 768w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_4-1024x933.png 1024w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_4.png 1045w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Das Niveau und die viertelj\u00e4hrliche Rate der Produktion pro Stunde, wie sie vom U.S. Bureau of Economic Analysis ver\u00f6ffentlicht werden, sind in Bezug auf die viertelj\u00e4hrlichen Ver\u00e4nderungsraten viel weniger volatil als das reale BIP. Warum dies so ist, ist die eigentliche Frage. K\u00f6nnte es sein, dass die Produktivit\u00e4t kurzfristig viel st\u00e4rker auf die Inflation und insbesondere auf die Inflationserwartungen reagiert als auf die allgemeine Wirtschaftst\u00e4tigkeit? Langfristige Analysen legen nahe, dass die Produktivit\u00e4t sehr viel schneller auf die allgemeine Konjunktur reagiert. In den letzten Jahren hat es eine starke Anpassung der Produktivit\u00e4t an das sektorale Umfeld gegeben, die nicht immer sofort in den makro\u00f6konomischen Daten (reales BIP) sichtbar war. Dies ist sicherlich darauf zur\u00fcckzuf\u00fchren, dass die Unternehmen \u00fcber neue Produkte und geeignete F\u00e4higkeiten zur Steigerung der Produktivit\u00e4t verf\u00fcgten \u2013 und auch weiterhin verf\u00fcgen werden \u2013, und zwar sowohl auf sektoraler als auch auf Unternehmensebene. Bekannt ist, dass bestimmte Sektoren im Laufe der Zeit verblassen, w\u00e4hrend andere auftauchen \u2013 man denke nur an die Ver\u00e4nderungen in der Automobilindustrie in der Vergangenheit im Vergleich zu den Erwartungen an die chipgesteuerte Automobilproduktion.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie man von Produktivit\u00e4ts\u00e4nderungen profitieren kann?<\/h2>\n\n\n\n<p>Wir erlauben uns, den Leser zu fragen, wie er\/sie von den erwarteten\/bef\u00fcrchteten Produktivit\u00e4tsver\u00e4nderungen profitieren kann?<\/p>\n\n\n\n<p>Eine recht arrogante Art, mit der Beantwortung dieser sehr heiklen Frage zu beginnen. Sie impliziert, dass man bevorzugt in Aktien investieren sollte, die in der Vergangenheit die besten Produktivit\u00e4tssteigerungen und eine koh\u00e4rente Reaktion auf signifikante Produktivit\u00e4tsver\u00e4nderungen gezeigt haben, d.h. in Aktien von Unternehmen, die Anzeichen einer Produktivit\u00e4tswende erkennen und schnell darauf reagieren?<\/p>\n\n\n\n<p>Wenn dieser Ansatz zu schwierig erscheint, gibt es einen anderen Weg, n\u00e4mlich die Verringerung des Engagements in Unternehmen und Branchen mit der schlechtesten Produktivit\u00e4tshistorie, entweder kurzfristig oder, was noch wichtiger ist, langfristig. Das kontextbezogene Argument besteht darin, die Tatsache ernst zu nehmen, dass Umschw\u00fcnge manchmal recht dramatisch sind, insbesondere bei Unternehmen oder Branchen mit hoher Schuldenlast. Ein dramatischer Produktivit\u00e4tsumschwung, wie wir ihn derzeit erleben, geht h\u00e4ufig mit einer verw\u00e4ssernden Finanzierung und einer hohen Schuldenlast einher. In einem solchen Fall lautet das inhaltliche Argument: man  \u201c<strong>Kaufe die Probleml\u00f6ser<\/strong>\u201d oder mit den entsprechenden Slogans: man  \u201c<strong>Investiere in die \u00c4rzte, nicht in die Patienten<\/strong>\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Schlussfolgerungen f\u00fcr Anleger<\/h2>\n\n\n\n<p>Unsere Schlussfolgerungen sollten als spezifische Folge einer au\u00dferordentlichen Verlagerung hin zu technologischen Innovationen und weg vom traditionellen \u201cOutput pro Arbeitsstunde\u201d gesehen werden. Wir sollten die Auswirkungen der neuen Technologien immer ernster nehmen.<\/p>\n\n\n\n<p>Dies bedeutet auch, dass Aktien selbst bei einer historisch niedrigen Inflationsrate von 2% weiterhin besser abschneiden w\u00fcrden als festverzinsliche Wertpapiere und Geldmarktinstrumente.<\/p>\n\n\n\n<p>Infolgedessen wird erwartet, dass der USD gegen\u00fcber dem EUR, YEN und GBP steigen wird. Die Tatsache, dass der CHF, EUR und JPY in letzter Zeit in recht engen Bandbreiten gegen\u00fcber dem USD schwankten, darf nicht unbeachtet bleiben, dass dunkle Wolken am W\u00e4hrungshimmel nichts Gutes verheissen &#8230;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_5-1024x616.png\" alt=\"\" class=\"wp-image-4282\" width=\"550\" srcset=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_5-1024x616.png 1024w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_5-300x180.png 300w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_5-768x462.png 768w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_5-1536x924.png 1536w, https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_5.png 1656w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p>Jeder Vorschlag ist h\u00f6chst willkommen.<\/p>\n\n\n\n<p><\/p>\n<span class=\"synved-social-container synved-social-container-share\"><a class=\"synved-social-button synved-social-button-share synved-social-size-24 synved-social-resolution-single synved-social-provider-facebook nolightbox\" data-provider=\"facebook\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Facebook\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fswisschange.ch%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4265%2F&#038;t=Erforderliche%20Hausaufgaben&#038;s=100&#038;p&#091;url&#093;=https%3A%2F%2Fswisschange.ch%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4265%2F&#038;p&#091;images&#093;&#091;0&#093;=https%3A%2F%2Fswisschange.ch%2Fwp-content%2Fuploads%2F2021%2F10%2FEMR_Okt21_Bild_1-1024x713.png&#038;p&#091;title&#093;=Erforderliche%20Hausaufgaben\" style=\"font-size: 0px;width:24px;height:24px;margin:0;margin-bottom:10px;margin-right:10px\"><img decoding=\"async\" alt=\"Facebook\" title=\"Share on Facebook\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"24\" height=\"24\" style=\"display: inline;width:24px;height:24px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/swisschange.ch\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/48x48\/facebook.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-24 synved-social-resolution-single synved-social-provider-twitter nolightbox\" data-provider=\"twitter\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fswisschange.ch%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4265%2F&#038;text=Hey%20check%20this%20out\" style=\"font-size: 0px;width:24px;height:24px;margin:0;margin-bottom:10px;margin-right:10px\"><img loading=\"lazy\" decoding=\"async\" alt=\"twitter\" title=\"Share on Twitter\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"24\" height=\"24\" style=\"display: inline;width:24px;height:24px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/swisschange.ch\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/48x48\/twitter.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-24 synved-social-resolution-single synved-social-provider-linkedin nolightbox\" data-provider=\"linkedin\" target=\"_blank\" rel=\"nofollow\" title=\"Share on Linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https%3A%2F%2Fswisschange.ch%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4265%2F&#038;title=Erforderliche%20Hausaufgaben\" style=\"font-size: 0px;width:24px;height:24px;margin:0;margin-bottom:10px;margin-right:10px\"><img loading=\"lazy\" decoding=\"async\" alt=\"linkedin\" title=\"Share on Linkedin\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"24\" height=\"24\" style=\"display: inline;width:24px;height:24px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/swisschange.ch\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/48x48\/linkedin.png\" \/><\/a><a class=\"synved-social-button synved-social-button-share synved-social-size-24 synved-social-resolution-single synved-social-provider-mail nolightbox\" data-provider=\"mail\" rel=\"nofollow\" title=\"Share by email\" href=\"mailto:?subject=Erforderliche%20Hausaufgaben&#038;body=Hey%20check%20this%20out:%20https%3A%2F%2Fswisschange.ch%2Ffr%2Fwp-json%2Fwp%2Fv2%2Fposts%2F4265%2F\" style=\"font-size: 0px;width:24px;height:24px;margin:0;margin-bottom:10px\"><img loading=\"lazy\" decoding=\"async\" alt=\"mail\" title=\"Share by email\" class=\"synved-share-image synved-social-image synved-social-image-share\" width=\"24\" height=\"24\" style=\"display: inline;width:24px;height:24px;margin: 0;padding: 0;border: none;box-shadow: none\" src=\"https:\/\/swisschange.ch\/wp-content\/plugins\/social-media-feather\/synved-social\/addons\/extra-icons\/image\/social\/clearslate\/48x48\/mail.png\" \/><\/a><\/span>","protected":false},"excerpt":{"rendered":"<p>Die Investitionsaussichten sind eher d\u00fcster, was vor allem \u00ad\u2013 aber nicht nur \u2013 auf die r\u00fcckl\u00e4ufige Produktivit\u00e4t, auf Angst vor steigender Inflation, eine hohe und wachsende Staatsverschuldung sowie auf \u201cungerechtfertigte\u201d \u00c4ngste vor einer baldigen Korrektur am Aktienmarkt zur\u00fcckzuf\u00fchren ist.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-4265","post","type-post","status-publish","format-standard","hentry","category-emr"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.9 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Adriano Zanoni\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SWISSCHANGE Financial Services AG | Hypotheken und Verm\u00f6gensverwaltung\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Erforderliche Hausaufgaben | SWISSCHANGE Financial Services AG\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2018\/10\/Home_Swisschange.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/swisschange.ch\/wp-content\/uploads\/2018\/10\/Home_Swisschange.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-10-26T07:04:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-10-26T08:27:55+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/swisschange\/\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#article\",\"name\":\"Erforderliche Hausaufgaben | SWISSCHANGE Financial Services AG\",\"headline\":\"Erforderliche Hausaufgaben\",\"author\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/author\\\/zanoni\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/EMR_Okt21_Bild_1.png\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#articleImage\",\"width\":1496,\"height\":1041},\"datePublished\":\"2021-10-26T09:04:47+02:00\",\"dateModified\":\"2021-10-26T10:27:55+02:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#webpage\"},\"articleSection\":\"EMR, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/category\\\/emr\\\/#listItem\",\"name\":\"EMR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/category\\\/emr\\\/#listItem\",\"position\":2,\"name\":\"EMR\",\"item\":\"https:\\\/\\\/swisschange.ch\\\/category\\\/emr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#listItem\",\"name\":\"Erforderliche Hausaufgaben\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#listItem\",\"position\":3,\"name\":\"Erforderliche Hausaufgaben\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/category\\\/emr\\\/#listItem\",\"name\":\"EMR\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/#organization\",\"name\":\"SWISSCHANGE Financial Services AG\",\"description\":\"Hypotheken und Verm\\u00f6gensverwaltung\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/\",\"telephone\":\"+41612640050\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/JCSCWM55-20-Jahre-Logo.svg\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#organizationLogo\",\"width\":269,\"height\":68,\"caption\":\"SWISSCHANGE Financial Services AG\"},\"image\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/swisschange\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/38153551\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/author\\\/zanoni\\\/#author\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/author\\\/zanoni\\\/\",\"name\":\"Adriano Zanoni\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#webpage\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/\",\"name\":\"Erforderliche Hausaufgaben | SWISSCHANGE Financial Services AG\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/2021\\\/10\\\/26\\\/erforderliche-hausaufgaben\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/author\\\/zanoni\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/author\\\/zanoni\\\/#author\"},\"datePublished\":\"2021-10-26T09:04:47+02:00\",\"dateModified\":\"2021-10-26T10:27:55+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/\",\"name\":\"SWISSCHANGE Financial Services AG\",\"description\":\"Hypotheken und Verm\\u00f6gensverwaltung\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/swisschange.ch\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Erforderliche Hausaufgaben | SWISSCHANGE Financial Services AG<\/title>\n\n","aioseo_head_json":{"title":"Erforderliche Hausaufgaben | SWISSCHANGE Financial Services AG","description":"","canonical_url":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#article","name":"Erforderliche Hausaufgaben | SWISSCHANGE Financial Services AG","headline":"Erforderliche Hausaufgaben","author":{"@id":"https:\/\/swisschange.ch\/fr\/author\/zanoni\/#author"},"publisher":{"@id":"https:\/\/swisschange.ch\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/swisschange.ch\/wp-content\/uploads\/2021\/10\/EMR_Okt21_Bild_1.png","@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#articleImage","width":1496,"height":1041},"datePublished":"2021-10-26T09:04:47+02:00","dateModified":"2021-10-26T10:27:55+02:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#webpage"},"isPartOf":{"@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#webpage"},"articleSection":"EMR, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/swisschange.ch\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/category\/emr\/#listItem","name":"EMR"}},{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/category\/emr\/#listItem","position":2,"name":"EMR","item":"https:\/\/swisschange.ch\/category\/emr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#listItem","name":"Erforderliche Hausaufgaben"},"previousItem":{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#listItem","position":3,"name":"Erforderliche Hausaufgaben","previousItem":{"@type":"ListItem","@id":"https:\/\/swisschange.ch\/category\/emr\/#listItem","name":"EMR"}}]},{"@type":"Organization","@id":"https:\/\/swisschange.ch\/fr\/#organization","name":"SWISSCHANGE Financial Services AG","description":"Hypotheken und Verm\u00f6gensverwaltung","url":"https:\/\/swisschange.ch\/fr\/","telephone":"+41612640050","logo":{"@type":"ImageObject","url":"https:\/\/swisschange.ch\/wp-content\/uploads\/2020\/01\/JCSCWM55-20-Jahre-Logo.svg","@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#organizationLogo","width":269,"height":68,"caption":"SWISSCHANGE Financial Services AG"},"image":{"@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/swisschange\/","https:\/\/www.linkedin.com\/company\/38153551\/"]},{"@type":"Person","@id":"https:\/\/swisschange.ch\/fr\/author\/zanoni\/#author","url":"https:\/\/swisschange.ch\/fr\/author\/zanoni\/","name":"Adriano Zanoni"},{"@type":"WebPage","@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#webpage","url":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/","name":"Erforderliche Hausaufgaben | SWISSCHANGE Financial Services AG","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/swisschange.ch\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/#breadcrumblist"},"author":{"@id":"https:\/\/swisschange.ch\/fr\/author\/zanoni\/#author"},"creator":{"@id":"https:\/\/swisschange.ch\/fr\/author\/zanoni\/#author"},"datePublished":"2021-10-26T09:04:47+02:00","dateModified":"2021-10-26T10:27:55+02:00"},{"@type":"WebSite","@id":"https:\/\/swisschange.ch\/fr\/#website","url":"https:\/\/swisschange.ch\/fr\/","name":"SWISSCHANGE Financial Services AG","description":"Hypotheken und Verm\u00f6gensverwaltung","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/swisschange.ch\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"SWISSCHANGE Financial Services AG | Hypotheken und Verm\u00f6gensverwaltung","og:type":"article","og:title":"Erforderliche Hausaufgaben | SWISSCHANGE Financial Services AG","og:url":"https:\/\/swisschange.ch\/fr\/2021\/10\/26\/erforderliche-hausaufgaben\/","og:image":"https:\/\/swisschange.ch\/wp-content\/uploads\/2018\/10\/Home_Swisschange.jpg","og:image:secure_url":"https:\/\/swisschange.ch\/wp-content\/uploads\/2018\/10\/Home_Swisschange.jpg","og:image:width":1500,"og:image:height":1001,"article:published_time":"2021-10-26T07:04:47+00:00","article:modified_time":"2021-10-26T08:27:55+00:00","article:publisher":"https:\/\/www.facebook.com\/swisschange\/"},"aioseo_meta_data":{"post_id":"4265","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-05-22 09:39:05","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":null,"created":"2021-10-26 06:57:46","updated":"2026-05-22 09:39:05"},"_links":{"self":[{"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/posts\/4265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/comments?post=4265"}],"version-history":[{"count":0,"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/posts\/4265\/revisions"}],"wp:attachment":[{"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/media?parent=4265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/categories?post=4265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swisschange.ch\/fr\/wp-json\/wp\/v2\/tags?post=4265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}